{"id":4860,"date":"2023-04-07T06:59:00","date_gmt":"2023-04-06T20:59:00","guid":{"rendered":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/?p=4860"},"modified":"2023-04-07T06:59:00","modified_gmt":"2023-04-06T20:59:00","slug":"service-booklet-for-good-friday-2023","status":"publish","type":"post","link":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/service-booklet-for-good-friday-2023\/","title":{"rendered":"Service Booklet for Good Friday 2023"},"content":{"rendered":"<p><a href=\"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/wp-content\/uploads\/2023\/04\/2023-SGEI-Good-Friday-Service-Booklet-FA.pdf\" target=\"_blank\" rel=\"noopener\">Click here to view booklet<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Click here to view booklet<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4860","post","type-post","status-publish","format-standard","hentry","category-churchnews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Service Booklet for Good Friday 2023 - St George&#039;s East Ivanhoe Website<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/service-booklet-for-good-friday-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Service Booklet for Good Friday 2023 - St George&#039;s East Ivanhoe Website\" \/>\n<meta property=\"og:description\" content=\"Click here to view booklet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/service-booklet-for-good-friday-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"St George&#039;s East Ivanhoe Website\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/StGeorgesEastIvanhoe\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-06T20:59:00+00:00\" \/>\n<meta name=\"author\" content=\"Parish Administrator\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Parish Administrator\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/service-booklet-for-good-friday-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/service-booklet-for-good-friday-2023\\\/\"},\"author\":{\"name\":\"Parish Administrator\",\"@id\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/#\\\/schema\\\/person\\\/e378f6750b9e9bbdf43941d3cbd8980c\"},\"headline\":\"Service Booklet for Good Friday 2023\",\"datePublished\":\"2023-04-06T20:59:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/service-booklet-for-good-friday-2023\\\/\"},\"wordCount\":10,\"publisher\":{\"@id\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/#organization\"},\"articleSection\":[\"Church News\"],\"inLanguage\":\"en-AU\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/service-booklet-for-good-friday-2023\\\/\",\"url\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/service-booklet-for-good-friday-2023\\\/\",\"name\":\"Service Booklet for Good Friday 2023 - St George&#039;s East Ivanhoe Website\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/#website\"},\"datePublished\":\"2023-04-06T20:59:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/service-booklet-for-good-friday-2023\\\/#breadcrumb\"},\"inLanguage\":\"en-AU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/service-booklet-for-good-friday-2023\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/service-booklet-for-good-friday-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Service Booklet for Good Friday 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/\",\"name\":\"St George's East Ivanhoe Website\",\"description\":\"The Church at the heart of the village\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-AU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/#organization\",\"name\":\"St George's East Ivanhoe\",\"url\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-AU\",\"@id\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/sgd.jpg\",\"contentUrl\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/sgd.jpg\",\"width\":135,\"height\":90,\"caption\":\"St George's East Ivanhoe\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/StGeorgesEastIvanhoe\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.stgeorgeseastivanhoe.org\\\/wordpress\\\/#\\\/schema\\\/person\\\/e378f6750b9e9bbdf43941d3cbd8980c\",\"name\":\"Parish Administrator\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-AU\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d436c0ca923da122a84a645a40e06fba6b8f4812964bba82fe9437ce42bc8e53?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d436c0ca923da122a84a645a40e06fba6b8f4812964bba82fe9437ce42bc8e53?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d436c0ca923da122a84a645a40e06fba6b8f4812964bba82fe9437ce42bc8e53?s=96&d=mm&r=g\",\"caption\":\"Parish Administrator\"},\"sameAs\":[\"http:\\\/\\\/stgeorgeseastivanhoe.org\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Service Booklet for Good Friday 2023 - St George&#039;s East Ivanhoe Website","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/service-booklet-for-good-friday-2023\/","og_locale":"en_US","og_type":"article","og_title":"Service Booklet for Good Friday 2023 - St George&#039;s East Ivanhoe Website","og_description":"Click here to view booklet","og_url":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/service-booklet-for-good-friday-2023\/","og_site_name":"St George&#039;s East Ivanhoe Website","article_publisher":"https:\/\/www.facebook.com\/StGeorgesEastIvanhoe","article_published_time":"2023-04-06T20:59:00+00:00","author":"Parish Administrator","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Parish Administrator"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/service-booklet-for-good-friday-2023\/#article","isPartOf":{"@id":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/service-booklet-for-good-friday-2023\/"},"author":{"name":"Parish Administrator","@id":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/#\/schema\/person\/e378f6750b9e9bbdf43941d3cbd8980c"},"headline":"Service Booklet for Good Friday 2023","datePublished":"2023-04-06T20:59:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/service-booklet-for-good-friday-2023\/"},"wordCount":10,"publisher":{"@id":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/#organization"},"articleSection":["Church News"],"inLanguage":"en-AU"},{"@type":"WebPage","@id":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/service-booklet-for-good-friday-2023\/","url":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/service-booklet-for-good-friday-2023\/","name":"Service Booklet for Good Friday 2023 - St George&#039;s East Ivanhoe Website","isPartOf":{"@id":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/#website"},"datePublished":"2023-04-06T20:59:00+00:00","breadcrumb":{"@id":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/service-booklet-for-good-friday-2023\/#breadcrumb"},"inLanguage":"en-AU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/service-booklet-for-good-friday-2023\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/service-booklet-for-good-friday-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Service Booklet for Good Friday 2023"}]},{"@type":"WebSite","@id":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/#website","url":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/","name":"St George's East Ivanhoe Website","description":"The Church at the heart of the village","publisher":{"@id":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-AU"},{"@type":"Organization","@id":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/#organization","name":"St George's East Ivanhoe","url":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"en-AU","@id":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/wp-content\/uploads\/2014\/11\/sgd.jpg","contentUrl":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/wp-content\/uploads\/2014\/11\/sgd.jpg","width":135,"height":90,"caption":"St George's East Ivanhoe"},"image":{"@id":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/StGeorgesEastIvanhoe"]},{"@type":"Person","@id":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/#\/schema\/person\/e378f6750b9e9bbdf43941d3cbd8980c","name":"Parish Administrator","image":{"@type":"ImageObject","inLanguage":"en-AU","@id":"https:\/\/secure.gravatar.com\/avatar\/d436c0ca923da122a84a645a40e06fba6b8f4812964bba82fe9437ce42bc8e53?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d436c0ca923da122a84a645a40e06fba6b8f4812964bba82fe9437ce42bc8e53?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d436c0ca923da122a84a645a40e06fba6b8f4812964bba82fe9437ce42bc8e53?s=96&d=mm&r=g","caption":"Parish Administrator"},"sameAs":["http:\/\/stgeorgeseastivanhoe.org"]}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/wp-json\/wp\/v2\/posts\/4860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/wp-json\/wp\/v2\/comments?post=4860"}],"version-history":[{"count":1,"href":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/wp-json\/wp\/v2\/posts\/4860\/revisions"}],"predecessor-version":[{"id":4862,"href":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/wp-json\/wp\/v2\/posts\/4860\/revisions\/4862"}],"wp:attachment":[{"href":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/wp-json\/wp\/v2\/media?parent=4860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/wp-json\/wp\/v2\/categories?post=4860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stgeorgeseastivanhoe.org\/wordpress\/wp-json\/wp\/v2\/tags?post=4860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}